{"id":11728,"date":"2023-04-21T16:43:37","date_gmt":"2023-04-21T08:43:37","guid":{"rendered":"https:\/\/designpedia.com.hk\/?post_type=latest_article&#038;p=11728"},"modified":"2023-05-25T15:32:19","modified_gmt":"2023-05-25T07:32:19","slug":"%e5%bf%85%e5%ad%b8%e5%bb%9a%e6%88%bf%e6%94%b6%e7%b4%8d%e5%a4%a7%e6%b3%95%ef%b8%b03%e5%a4%a7%e6%94%b6%e7%b4%8d%e9%87%8d%e9%bb%9e%e6%89%93%e9%80%a0%e6%95%b4%e6%bd%94%e6%9c%89%e5%ba%8f%e7%9a%84%e5%bb%9a","status":"publish","type":"latest_article","link":"https:\/\/designpedia.com.hk\/tc\/latest_article\/%e5%bf%85%e5%ad%b8%e5%bb%9a%e6%88%bf%e6%94%b6%e7%b4%8d%e5%a4%a7%e6%b3%95%ef%b8%b03%e5%a4%a7%e6%94%b6%e7%b4%8d%e9%87%8d%e9%bb%9e%e6%89%93%e9%80%a0%e6%95%b4%e6%bd%94%e6%9c%89%e5%ba%8f%e7%9a%84%e5%bb%9a\/","title":{"rendered":"\u5fc5\u5b78\u5eda\u623f\u6536\u7d0d\u5927\u6cd5\ufe303\u5927\u6536\u7d0d\u91cd\u9ede\u6253\u9020\u6574\u6f54\u6709\u5e8f\u7684\u5eda\u623f"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","class_list":["post-11728","latest_article","type-latest_article","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u5fc5\u5b78\u5eda\u623f\u6536\u7d0d\u5927\u6cd5\ufe303\u5927\u6536\u7d0d\u91cd\u9ede\u6253\u9020\u6574\u6f54\u6709\u5e8f\u7684\u5eda\u623f<\/title>\n<meta name=\"description\" content=\"\u4e0d\u8ad6\u4f60\u662f\u5426\u6bcf\u5929\u90fd\u6703\u4e0b\u5eda\uff0c\u76f8\u4fe1\u4f60\u4e5f\u6703\u540c\u610f\ufe30\u505a\u98ef\u672c\u8eab\u4e0d\u7b97\u56f0\u96e3\uff0c\u56f0\u96e3\u4e4b\u8655\u5728\u65bc\u5eda\u623f\u7684\u6e05\u6f54\u53ca\u6253\u7406\u3002\u82e5\u4f60\u6c92\u6709\u5148\u505a\u597d\u5eda\u623f\u6536\u7d0d\uff0c\u7528\u5b8c\u7897\u789f\u3001\u5eda\u5177\u5f8c\u4e0d\u77e5\u653e\u56de\u4f55\u8655\uff0c\u4e45\u800c\u4e45\u4e4b\u4fbf\u6703\u6108\u4f86\u6108\u6df7\u4e82\u3002\u5bb6\u5eab Designpedia\u70ba\u5927\u5bb6\u5206\u4eab\u5eda\u623f\u6536\u7d0d3\u5927\u6280\u5de7\uff0c\u8b93\u4f60\u5728\u4e00\u500b\u6574\u6f54\u6709\u5e8f\u7684\u5eda\u623f\u716e\u51fa\u7f8e\u98df\u4f73\u991a\uff01\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/designpedia.com.hk\/latest_article\/\u5fc5\u5b78\u5eda\u623f\u6536\u7d0d\u5927\u6cd5\ufe303\u5927\u6536\u7d0d\u91cd\u9ede\u6253\u9020\u6574\u6f54\u6709\u5e8f\u7684\u5eda\/\" \/>\n<meta property=\"og:locale\" content=\"zh_HK\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u5fc5\u5b78\u5eda\u623f\u6536\u7d0d\u5927\u6cd5\ufe303\u5927\u6536\u7d0d\u91cd\u9ede\u6253\u9020\u6574\u6f54\u6709\u5e8f\u7684\u5eda\u623f\" \/>\n<meta property=\"og:description\" content=\"\u4e0d\u8ad6\u4f60\u662f\u5426\u6bcf\u5929\u90fd\u6703\u4e0b\u5eda\uff0c\u76f8\u4fe1\u4f60\u4e5f\u6703\u540c\u610f\ufe30\u505a\u98ef\u672c\u8eab\u4e0d\u7b97\u56f0\u96e3\uff0c\u56f0\u96e3\u4e4b\u8655\u5728\u65bc\u5eda\u623f\u7684\u6e05\u6f54\u53ca\u6253\u7406\u3002\u82e5\u4f60\u6c92\u6709\u5148\u505a\u597d\u5eda\u623f\u6536\u7d0d\uff0c\u7528\u5b8c\u7897\u789f\u3001\u5eda\u5177\u5f8c\u4e0d\u77e5\u653e\u56de\u4f55\u8655\uff0c\u4e45\u800c\u4e45\u4e4b\u4fbf\u6703\u6108\u4f86\u6108\u6df7\u4e82\u3002\u5bb6\u5eab Designpedia\u70ba\u5927\u5bb6\u5206\u4eab\u5eda\u623f\u6536\u7d0d3\u5927\u6280\u5de7\uff0c\u8b93\u4f60\u5728\u4e00\u500b\u6574\u6f54\u6709\u5e8f\u7684\u5eda\u623f\u716e\u51fa\u7f8e\u98df\u4f73\u991a\uff01\" \/>\n<meta property=\"og:url\" content=\"https:\/\/designpedia.com.hk\/latest_article\/\u5fc5\u5b78\u5eda\u623f\u6536\u7d0d\u5927\u6cd5\ufe303\u5927\u6536\u7d0d\u91cd\u9ede\u6253\u9020\u6574\u6f54\u6709\u5e8f\u7684\u5eda\/\" \/>\n<meta property=\"og:site_name\" content=\"Designpedia\uff5c\u5bb6\u5eab \u4e00\u7ad9\u5f0f\u8a2d\u8a08\u88dd\u4fee\u914d\u5c0d\u5e73\u53f0\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/designpediahk\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-25T07:32:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/designpedia.com.hk\/wp-content\/uploads\/2023\/01\/Bellagio-\u78a7\u5824\u534a\u5cf6-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1334\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/designpedia.com.hk\\\/latest_article\\\/%e5%bf%85%e5%ad%b8%e5%bb%9a%e6%88%bf%e6%94%b6%e7%b4%8d%e5%a4%a7%e6%b3%95%ef%b8%b03%e5%a4%a7%e6%94%b6%e7%b4%8d%e9%87%8d%e9%bb%9e%e6%89%93%e9%80%a0%e6%95%b4%e6%bd%94%e6%9c%89%e5%ba%8f%e7%9a%84%e5%bb%9a\\\/\",\"url\":\"https:\\\/\\\/designpedia.com.hk\\\/latest_article\\\/%e5%bf%85%e5%ad%b8%e5%bb%9a%e6%88%bf%e6%94%b6%e7%b4%8d%e5%a4%a7%e6%b3%95%ef%b8%b03%e5%a4%a7%e6%94%b6%e7%b4%8d%e9%87%8d%e9%bb%9e%e6%89%93%e9%80%a0%e6%95%b4%e6%bd%94%e6%9c%89%e5%ba%8f%e7%9a%84%e5%bb%9a\\\/\",\"name\":\"\u5fc5\u5b78\u5eda\u623f\u6536\u7d0d\u5927\u6cd5\ufe303\u5927\u6536\u7d0d\u91cd\u9ede\u6253\u9020\u6574\u6f54\u6709\u5e8f\u7684\u5eda\u623f\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/designpedia.com.hk\\\/#website\"},\"datePublished\":\"2023-04-21T08:43:37+00:00\",\"dateModified\":\"2023-05-25T07:32:19+00:00\",\"description\":\"\u4e0d\u8ad6\u4f60\u662f\u5426\u6bcf\u5929\u90fd\u6703\u4e0b\u5eda\uff0c\u76f8\u4fe1\u4f60\u4e5f\u6703\u540c\u610f\ufe30\u505a\u98ef\u672c\u8eab\u4e0d\u7b97\u56f0\u96e3\uff0c\u56f0\u96e3\u4e4b\u8655\u5728\u65bc\u5eda\u623f\u7684\u6e05\u6f54\u53ca\u6253\u7406\u3002\u82e5\u4f60\u6c92\u6709\u5148\u505a\u597d\u5eda\u623f\u6536\u7d0d\uff0c\u7528\u5b8c\u7897\u789f\u3001\u5eda\u5177\u5f8c\u4e0d\u77e5\u653e\u56de\u4f55\u8655\uff0c\u4e45\u800c\u4e45\u4e4b\u4fbf\u6703\u6108\u4f86\u6108\u6df7\u4e82\u3002\u5bb6\u5eab Designpedia\u70ba\u5927\u5bb6\u5206\u4eab\u5eda\u623f\u6536\u7d0d3\u5927\u6280\u5de7\uff0c\u8b93\u4f60\u5728\u4e00\u500b\u6574\u6f54\u6709\u5e8f\u7684\u5eda\u623f\u716e\u51fa\u7f8e\u98df\u4f73\u991a\uff01\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/designpedia.com.hk\\\/latest_article\\\/%e5%bf%85%e5%ad%b8%e5%bb%9a%e6%88%bf%e6%94%b6%e7%b4%8d%e5%a4%a7%e6%b3%95%ef%b8%b03%e5%a4%a7%e6%94%b6%e7%b4%8d%e9%87%8d%e9%bb%9e%e6%89%93%e9%80%a0%e6%95%b4%e6%bd%94%e6%9c%89%e5%ba%8f%e7%9a%84%e5%bb%9a\\\/#breadcrumb\"},\"inLanguage\":\"zh-HK\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/designpedia.com.hk\\\/latest_article\\\/%e5%bf%85%e5%ad%b8%e5%bb%9a%e6%88%bf%e6%94%b6%e7%b4%8d%e5%a4%a7%e6%b3%95%ef%b8%b03%e5%a4%a7%e6%94%b6%e7%b4%8d%e9%87%8d%e9%bb%9e%e6%89%93%e9%80%a0%e6%95%b4%e6%bd%94%e6%9c%89%e5%ba%8f%e7%9a%84%e5%bb%9a\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/designpedia.com.hk\\\/latest_article\\\/%e5%bf%85%e5%ad%b8%e5%bb%9a%e6%88%bf%e6%94%b6%e7%b4%8d%e5%a4%a7%e6%b3%95%ef%b8%b03%e5%a4%a7%e6%94%b6%e7%b4%8d%e9%87%8d%e9%bb%9e%e6%89%93%e9%80%a0%e6%95%b4%e6%bd%94%e6%9c%89%e5%ba%8f%e7%9a%84%e5%bb%9a\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/designpedia.com.hk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u5fc5\u5b78\u5eda\u623f\u6536\u7d0d\u5927\u6cd5\ufe303\u5927\u6536\u7d0d\u91cd\u9ede\u6253\u9020\u6574\u6f54\u6709\u5e8f\u7684\u5eda\u623f\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/designpedia.com.hk\\\/#website\",\"url\":\"https:\\\/\\\/designpedia.com.hk\\\/\",\"name\":\"Designpedia\uff5c\u5bb6\u5eab \u4e00\u7ad9\u5f0f\u8a2d\u8a08\u88dd\u4fee\u914d\u5c0d\u5e73\u53f0\",\"description\":\"Designpedia\uff5c\u5bb6\u5eab \u4e00\u7ad9\u5f0f\u8a2d\u8a08\u88dd\u4fee\u914d\u5c0d\u5e73\u53f0\",\"publisher\":{\"@id\":\"https:\\\/\\\/designpedia.com.hk\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/designpedia.com.hk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-HK\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/designpedia.com.hk\\\/#organization\",\"name\":\"Designpedia\uff5c\u5bb6\u5eab \u4e00\u7ad9\u5f0f\u8a2d\u8a08\u88dd\u4fee\u914d\u5c0d\u5e73\u53f0\",\"url\":\"https:\\\/\\\/designpedia.com.hk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-HK\",\"@id\":\"https:\\\/\\\/designpedia.com.hk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/designpedia.com.hk\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Designpedia_logo_FB2_no_floor.png\",\"contentUrl\":\"https:\\\/\\\/designpedia.com.hk\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Designpedia_logo_FB2_no_floor.png\",\"width\":700,\"height\":700,\"caption\":\"Designpedia\uff5c\u5bb6\u5eab \u4e00\u7ad9\u5f0f\u8a2d\u8a08\u88dd\u4fee\u914d\u5c0d\u5e73\u53f0\"},\"image\":{\"@id\":\"https:\\\/\\\/designpedia.com.hk\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/designpediahk\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u5fc5\u5b78\u5eda\u623f\u6536\u7d0d\u5927\u6cd5\ufe303\u5927\u6536\u7d0d\u91cd\u9ede\u6253\u9020\u6574\u6f54\u6709\u5e8f\u7684\u5eda\u623f","description":"\u4e0d\u8ad6\u4f60\u662f\u5426\u6bcf\u5929\u90fd\u6703\u4e0b\u5eda\uff0c\u76f8\u4fe1\u4f60\u4e5f\u6703\u540c\u610f\ufe30\u505a\u98ef\u672c\u8eab\u4e0d\u7b97\u56f0\u96e3\uff0c\u56f0\u96e3\u4e4b\u8655\u5728\u65bc\u5eda\u623f\u7684\u6e05\u6f54\u53ca\u6253\u7406\u3002\u82e5\u4f60\u6c92\u6709\u5148\u505a\u597d\u5eda\u623f\u6536\u7d0d\uff0c\u7528\u5b8c\u7897\u789f\u3001\u5eda\u5177\u5f8c\u4e0d\u77e5\u653e\u56de\u4f55\u8655\uff0c\u4e45\u800c\u4e45\u4e4b\u4fbf\u6703\u6108\u4f86\u6108\u6df7\u4e82\u3002\u5bb6\u5eab Designpedia\u70ba\u5927\u5bb6\u5206\u4eab\u5eda\u623f\u6536\u7d0d3\u5927\u6280\u5de7\uff0c\u8b93\u4f60\u5728\u4e00\u500b\u6574\u6f54\u6709\u5e8f\u7684\u5eda\u623f\u716e\u51fa\u7f8e\u98df\u4f73\u991a\uff01","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/designpedia.com.hk\/latest_article\/\u5fc5\u5b78\u5eda\u623f\u6536\u7d0d\u5927\u6cd5\ufe303\u5927\u6536\u7d0d\u91cd\u9ede\u6253\u9020\u6574\u6f54\u6709\u5e8f\u7684\u5eda\/","og_locale":"zh_HK","og_type":"article","og_title":"\u5fc5\u5b78\u5eda\u623f\u6536\u7d0d\u5927\u6cd5\ufe303\u5927\u6536\u7d0d\u91cd\u9ede\u6253\u9020\u6574\u6f54\u6709\u5e8f\u7684\u5eda\u623f","og_description":"\u4e0d\u8ad6\u4f60\u662f\u5426\u6bcf\u5929\u90fd\u6703\u4e0b\u5eda\uff0c\u76f8\u4fe1\u4f60\u4e5f\u6703\u540c\u610f\ufe30\u505a\u98ef\u672c\u8eab\u4e0d\u7b97\u56f0\u96e3\uff0c\u56f0\u96e3\u4e4b\u8655\u5728\u65bc\u5eda\u623f\u7684\u6e05\u6f54\u53ca\u6253\u7406\u3002\u82e5\u4f60\u6c92\u6709\u5148\u505a\u597d\u5eda\u623f\u6536\u7d0d\uff0c\u7528\u5b8c\u7897\u789f\u3001\u5eda\u5177\u5f8c\u4e0d\u77e5\u653e\u56de\u4f55\u8655\uff0c\u4e45\u800c\u4e45\u4e4b\u4fbf\u6703\u6108\u4f86\u6108\u6df7\u4e82\u3002\u5bb6\u5eab Designpedia\u70ba\u5927\u5bb6\u5206\u4eab\u5eda\u623f\u6536\u7d0d3\u5927\u6280\u5de7\uff0c\u8b93\u4f60\u5728\u4e00\u500b\u6574\u6f54\u6709\u5e8f\u7684\u5eda\u623f\u716e\u51fa\u7f8e\u98df\u4f73\u991a\uff01","og_url":"https:\/\/designpedia.com.hk\/latest_article\/\u5fc5\u5b78\u5eda\u623f\u6536\u7d0d\u5927\u6cd5\ufe303\u5927\u6536\u7d0d\u91cd\u9ede\u6253\u9020\u6574\u6f54\u6709\u5e8f\u7684\u5eda\/","og_site_name":"Designpedia\uff5c\u5bb6\u5eab \u4e00\u7ad9\u5f0f\u8a2d\u8a08\u88dd\u4fee\u914d\u5c0d\u5e73\u53f0","article_publisher":"https:\/\/www.facebook.com\/designpediahk","article_modified_time":"2023-05-25T07:32:19+00:00","og_image":[{"width":2000,"height":1334,"url":"https:\/\/designpedia.com.hk\/wp-content\/uploads\/2023\/01\/Bellagio-\u78a7\u5824\u534a\u5cf6-4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/designpedia.com.hk\/latest_article\/%e5%bf%85%e5%ad%b8%e5%bb%9a%e6%88%bf%e6%94%b6%e7%b4%8d%e5%a4%a7%e6%b3%95%ef%b8%b03%e5%a4%a7%e6%94%b6%e7%b4%8d%e9%87%8d%e9%bb%9e%e6%89%93%e9%80%a0%e6%95%b4%e6%bd%94%e6%9c%89%e5%ba%8f%e7%9a%84%e5%bb%9a\/","url":"https:\/\/designpedia.com.hk\/latest_article\/%e5%bf%85%e5%ad%b8%e5%bb%9a%e6%88%bf%e6%94%b6%e7%b4%8d%e5%a4%a7%e6%b3%95%ef%b8%b03%e5%a4%a7%e6%94%b6%e7%b4%8d%e9%87%8d%e9%bb%9e%e6%89%93%e9%80%a0%e6%95%b4%e6%bd%94%e6%9c%89%e5%ba%8f%e7%9a%84%e5%bb%9a\/","name":"\u5fc5\u5b78\u5eda\u623f\u6536\u7d0d\u5927\u6cd5\ufe303\u5927\u6536\u7d0d\u91cd\u9ede\u6253\u9020\u6574\u6f54\u6709\u5e8f\u7684\u5eda\u623f","isPartOf":{"@id":"https:\/\/designpedia.com.hk\/#website"},"datePublished":"2023-04-21T08:43:37+00:00","dateModified":"2023-05-25T07:32:19+00:00","description":"\u4e0d\u8ad6\u4f60\u662f\u5426\u6bcf\u5929\u90fd\u6703\u4e0b\u5eda\uff0c\u76f8\u4fe1\u4f60\u4e5f\u6703\u540c\u610f\ufe30\u505a\u98ef\u672c\u8eab\u4e0d\u7b97\u56f0\u96e3\uff0c\u56f0\u96e3\u4e4b\u8655\u5728\u65bc\u5eda\u623f\u7684\u6e05\u6f54\u53ca\u6253\u7406\u3002\u82e5\u4f60\u6c92\u6709\u5148\u505a\u597d\u5eda\u623f\u6536\u7d0d\uff0c\u7528\u5b8c\u7897\u789f\u3001\u5eda\u5177\u5f8c\u4e0d\u77e5\u653e\u56de\u4f55\u8655\uff0c\u4e45\u800c\u4e45\u4e4b\u4fbf\u6703\u6108\u4f86\u6108\u6df7\u4e82\u3002\u5bb6\u5eab Designpedia\u70ba\u5927\u5bb6\u5206\u4eab\u5eda\u623f\u6536\u7d0d3\u5927\u6280\u5de7\uff0c\u8b93\u4f60\u5728\u4e00\u500b\u6574\u6f54\u6709\u5e8f\u7684\u5eda\u623f\u716e\u51fa\u7f8e\u98df\u4f73\u991a\uff01","breadcrumb":{"@id":"https:\/\/designpedia.com.hk\/latest_article\/%e5%bf%85%e5%ad%b8%e5%bb%9a%e6%88%bf%e6%94%b6%e7%b4%8d%e5%a4%a7%e6%b3%95%ef%b8%b03%e5%a4%a7%e6%94%b6%e7%b4%8d%e9%87%8d%e9%bb%9e%e6%89%93%e9%80%a0%e6%95%b4%e6%bd%94%e6%9c%89%e5%ba%8f%e7%9a%84%e5%bb%9a\/#breadcrumb"},"inLanguage":"zh-HK","potentialAction":[{"@type":"ReadAction","target":["https:\/\/designpedia.com.hk\/latest_article\/%e5%bf%85%e5%ad%b8%e5%bb%9a%e6%88%bf%e6%94%b6%e7%b4%8d%e5%a4%a7%e6%b3%95%ef%b8%b03%e5%a4%a7%e6%94%b6%e7%b4%8d%e9%87%8d%e9%bb%9e%e6%89%93%e9%80%a0%e6%95%b4%e6%bd%94%e6%9c%89%e5%ba%8f%e7%9a%84%e5%bb%9a\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/designpedia.com.hk\/latest_article\/%e5%bf%85%e5%ad%b8%e5%bb%9a%e6%88%bf%e6%94%b6%e7%b4%8d%e5%a4%a7%e6%b3%95%ef%b8%b03%e5%a4%a7%e6%94%b6%e7%b4%8d%e9%87%8d%e9%bb%9e%e6%89%93%e9%80%a0%e6%95%b4%e6%bd%94%e6%9c%89%e5%ba%8f%e7%9a%84%e5%bb%9a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/designpedia.com.hk\/"},{"@type":"ListItem","position":2,"name":"\u5fc5\u5b78\u5eda\u623f\u6536\u7d0d\u5927\u6cd5\ufe303\u5927\u6536\u7d0d\u91cd\u9ede\u6253\u9020\u6574\u6f54\u6709\u5e8f\u7684\u5eda\u623f"}]},{"@type":"WebSite","@id":"https:\/\/designpedia.com.hk\/#website","url":"https:\/\/designpedia.com.hk\/","name":"Designpedia\uff5c\u5bb6\u5eab \u4e00\u7ad9\u5f0f\u8a2d\u8a08\u88dd\u4fee\u914d\u5c0d\u5e73\u53f0","description":"Designpedia\uff5c\u5bb6\u5eab \u4e00\u7ad9\u5f0f\u8a2d\u8a08\u88dd\u4fee\u914d\u5c0d\u5e73\u53f0","publisher":{"@id":"https:\/\/designpedia.com.hk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/designpedia.com.hk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-HK"},{"@type":"Organization","@id":"https:\/\/designpedia.com.hk\/#organization","name":"Designpedia\uff5c\u5bb6\u5eab \u4e00\u7ad9\u5f0f\u8a2d\u8a08\u88dd\u4fee\u914d\u5c0d\u5e73\u53f0","url":"https:\/\/designpedia.com.hk\/","logo":{"@type":"ImageObject","inLanguage":"zh-HK","@id":"https:\/\/designpedia.com.hk\/#\/schema\/logo\/image\/","url":"https:\/\/designpedia.com.hk\/wp-content\/uploads\/2023\/03\/Designpedia_logo_FB2_no_floor.png","contentUrl":"https:\/\/designpedia.com.hk\/wp-content\/uploads\/2023\/03\/Designpedia_logo_FB2_no_floor.png","width":700,"height":700,"caption":"Designpedia\uff5c\u5bb6\u5eab \u4e00\u7ad9\u5f0f\u8a2d\u8a08\u88dd\u4fee\u914d\u5c0d\u5e73\u53f0"},"image":{"@id":"https:\/\/designpedia.com.hk\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/designpediahk"]}]}},"_links":{"self":[{"href":"https:\/\/designpedia.com.hk\/tc\/wp-json\/wp\/v2\/latest_article\/11728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/designpedia.com.hk\/tc\/wp-json\/wp\/v2\/latest_article"}],"about":[{"href":"https:\/\/designpedia.com.hk\/tc\/wp-json\/wp\/v2\/types\/latest_article"}],"version-history":[{"count":2,"href":"https:\/\/designpedia.com.hk\/tc\/wp-json\/wp\/v2\/latest_article\/11728\/revisions"}],"predecessor-version":[{"id":12337,"href":"https:\/\/designpedia.com.hk\/tc\/wp-json\/wp\/v2\/latest_article\/11728\/revisions\/12337"}],"wp:attachment":[{"href":"https:\/\/designpedia.com.hk\/tc\/wp-json\/wp\/v2\/media?parent=11728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}